{"id":9250,"date":"2022-12-21T00:41:24","date_gmt":"2022-12-21T00:41:24","guid":{"rendered":"http:\/\/dev.realoptions.net\/?p=9250"},"modified":"2026-04-19T22:58:05","modified_gmt":"2026-04-20T05:58:05","slug":"preguntas-frecuentes-sobre-la-sifilis","status":"publish","type":"post","link":"https:\/\/realoptions.net\/es\/preguntas-frecuentes-sobre-la-sifilis\/","title":{"rendered":"Preguntas Frecuentes Sobre la S\u00edfilis"},"content":{"rendered":"<p><img decoding=\"async\" class=\"wp-image-9252 size-full alignnone\" src=\"https:\/\/realoptions.net\/wp-content\/uploads\/2022\/12\/sypBlog.jpg\" alt=\"\" width=\"800\" height=\"534\" srcset=\"https:\/\/realoptions.net\/wp-content\/uploads\/2022\/12\/sypBlog.jpg 800w, https:\/\/realoptions.net\/wp-content\/uploads\/2022\/12\/sypBlog-300x200.jpg 300w, https:\/\/realoptions.net\/wp-content\/uploads\/2022\/12\/sypBlog-768x513.jpg 768w, https:\/\/realoptions.net\/wp-content\/uploads\/2022\/12\/sypBlog-320x214.jpg 320w, https:\/\/realoptions.net\/wp-content\/uploads\/2022\/12\/sypBlog-480x320.jpg 480w, https:\/\/realoptions.net\/wp-content\/uploads\/2022\/12\/sypBlog-272x182.jpg 272w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p>\n<h2>\u00bfQu\u00e9 es la s\u00edfilis?<\/h2>\n<p>La s\u00edfilis es una ETS que, si no se trata con cuidado, puede ser peligrosa y causar problemas a largo plazo. Para los adultos, la s\u00edfilis se divide en cuatro etapas de s\u00edntomas: s\u00edfilis primaria, s\u00edfilis secundaria, s\u00edfilis latente y s\u00edfilis en etapa tard\u00eda. En este art\u00edculo, brindaremos informaci\u00f3n sobre estas etapas y responderemos algunas preguntas comunes sobre la s\u00edfilis.<\/p>\n<h2>\u00bfC\u00f3mo contraen las personas la s\u00edfilis?<\/h2>\n<p>La s\u00edfilis se transmite a trav\u00e9s del contacto f\u00edsico con una llaga de s\u00edfilis, que se encuentra con mayor frecuencia en las \u00e1reas genitales externas, dentro de la vagina, debajo del prepucio del pene, en o alrededor del ano o en el recto. La s\u00edfilis tambi\u00e9n se puede transmitir de madre a hijo durante el embarazo.<\/p>\n<h2>\u00bfC\u00f3mo evito la s\u00edfilis?<\/h2>\n<p>La mejor manera de evitar la s\u00edfilis es practicar la abstinencia o usar un m\u00e9todo anticonceptivo de barrera, como un cond\u00f3n, cada vez que tenga relaciones sexuales. Adem\u00e1s, es aconsejable limitar el n\u00famero de parejas sexuales y asegurarse de que todas las parejas con las que tenga relaciones \u00edntimas se hayan sometido a pruebas de detecci\u00f3n de ETS.<\/p>\n<h2>\u00bfEstoy en riesgo de contraer s\u00edfilis?<\/h2>\n<p>Cualquier persona sexualmente activa, especialmente cualquiera que no est\u00e9 usando un m\u00e9todo anticonceptivo de barrera, corre el riesgo de contraer s\u00edfilis u otra ETS\/ITS.<\/p>\n<h2>\u00bfC\u00f3mo son los s\u00edntomas de la s\u00edfilis?<\/h2>\n<p>Varios s\u00edntomas de la s\u00edfilis pueden parecerse a los s\u00edntomas de otras ETS. De hecho, a veces se hace referencia a la s\u00edfilis como &#8220;la gran imitadora&#8221;. La s\u00edfilis puede aparecer de manera diferente seg\u00fan la etapa de los s\u00edntomas:<\/p>\n<ul>\n<li>En la s\u00edfilis primaria, puede aparecer una llaga llamada chancro en la piel donde ha entrado la bacteria. Esta llaga generalmente es indolora y puede confundirse con un vello encarnado o una espinilla.<\/li>\n<li>En la s\u00edfilis secundaria, puede experimentar una amplia variedad de s\u00edntomas, como sarpullido, fiebre, ganglios linf\u00e1ticos inflamados, fatiga, p\u00e9rdida de peso y dolores musculares.<\/li>\n<li>En la s\u00edfilis latente, es posible que no experimente ning\u00fan s\u00edntoma, pero a\u00fan puede transmitir la infecci\u00f3n a otras personas a trav\u00e9s del contacto sexual.<\/li>\n<li>En la etapa tard\u00eda de la s\u00edfilis, se pueden producir da\u00f1os graves en el coraz\u00f3n, el cerebro y otros \u00f3rganos que pueden provocar par\u00e1lisis, ceguera e incluso la muerte si no se tratan.<\/li>\n<\/ul>\n<h2>\u00bfC\u00f3mo puede la s\u00edfilis afectar a un beb\u00e9 por nacer?<\/h2>\n<p>Si una mujer embarazada tiene s\u00edfilis, se la puede transmitir al feto a trav\u00e9s de la placenta. Esto se conoce como s\u00edfilis cong\u00e9nita y puede causar serios problemas de salud en el beb\u00e9, incluido el nacimiento de un ni\u00f1o muerto o la muerte poco despu\u00e9s del nacimiento. Adem\u00e1s, el beb\u00e9 puede experimentar problemas de visi\u00f3n y audici\u00f3n, convulsiones, retraso mental y deformidades en los huesos.<\/p>\n<h2>\u00bfDeber\u00eda hacerme la prueba de s\u00edfilis?<\/h2>\n<p>S\u00ed. Es importante hacerse la prueba de s\u00edfilis si cree que puede haber estado expuesto a la infecci\u00f3n, ya que la detecci\u00f3n temprana es la mejor manera de evitar el da\u00f1o a largo plazo de la s\u00edfilis no tratada. Tambi\u00e9n es una buena idea hacerse la prueba regularmente si es sexualmente activo, ya que muchas personas con s\u00edfilis no experimentan ning\u00fan s\u00edntoma y es posible que no sepan que est\u00e1n infectadas. En RealOptions, proporcionamos pruebas para varias ETS\/ITS, incluida la s\u00edfilis. Tenemos cl\u00ednicas ubicadas en el <a href=\"https:\/\/www.google.com\/maps\/place\/RealOptions+Pregnancy+Medical+Clinics\/@37.2378655,-121.9328295,11z\/data=!4m8!1m2!2m1!1srealoptions!3m4!1s0x808e3397f17c7389:0xaffdf9bc837bb473!8m2!3d37.336805!4d-121.918747\" data-wpel-link=\"external\" target=\"_blank\" rel=\"nofollow external noopener noreferrer\">centro de San Jos\u00e9<\/a>, el <a href=\"https:\/\/www.google.com\/maps\/place\/RealOptions+Pregnancy+Medical+Clinics\/@37.2382472,-121.9328303,11z\/data=!4m8!1m2!2m1!1srealoptions!3m4!1s0x808fcd6de1174ba9:0xdb7449433bb522e1!8m2!3d37.366384!4d-121.8281184\" data-wpel-link=\"external\" target=\"_blank\" rel=\"nofollow external noopener noreferrer\">este de San Jos\u00e9<\/a>, <a href=\"https:\/\/www.google.com\/maps\/place\/RealOptions+Pregnancy+Medical+Clinics\/@37.591997,-122.1752777,11z\/data=!4m8!1m2!2m1!1srealoptions!3m4!1s0x808f9579b7afea7d:0xcd508106be553a1d!8m2!3d37.591997!4d-122.035202\" data-wpel-link=\"external\" target=\"_blank\" rel=\"nofollow external noopener noreferrer\">Union City<\/a>, <a href=\"https:\/\/www.google.com\/maps\/place\/RealOptions+Obria+Medical+Clinics+of+Oakland\/@37.8192747,-122.2648175,15z\/data=!4m5!3m4!1s0x0:0xb6d2b17ac44e7080!8m2!3d37.8191982!4d-122.2648115\" data-wpel-link=\"external\" target=\"_blank\" rel=\"nofollow external noopener noreferrer\">Oakland<\/a> y <a href=\"https:\/\/www.google.com\/maps\/place\/RealOptions+Obria+Medical+Clinics+of+Redwood+City\/@37.4881612,-122.2337365,15z\/data=!4m5!3m4!1s0x0:0x17f9efe705795315!8m2!3d37.4881612!4d-122.2337365?shorturl=1\" data-wpel-link=\"external\" target=\"_blank\" rel=\"nofollow external noopener noreferrer\">Redwood City<\/a>, por lo que siempre estamos cerca. Haga <a href=\"https:\/\/realoptions.net\/contact-us\/\" data-wpel-link=\"external\" target=\"_blank\" rel=\"nofollow external noopener noreferrer\">clic aqu\u00ed<\/a> para programar una prueba en una de nuestras ubicaciones<\/p>\n<h2>\u00bfC\u00f3mo es el proceso de prueba para la s\u00edfilis?<\/h2>\n<p>En RealOptions, nuestro proceso de prueba para la s\u00edfilis es simple y directo. Usamos <a href=\"https:\/\/www.questdiagnostics.com\/patients\/get-tested\/prepare\" data-wpel-link=\"external\" target=\"_blank\" rel=\"nofollow external noopener noreferrer\">Quest Diagnostics<\/a> para el trabajo de laboratorio y le proporcionaremos la solicitud de laboratorio requerida en su primera visita. Dependiendo de los resultados, podemos recomendar pruebas de seguimiento o consultas adicionales. Nuestro personal est\u00e1 disponible para responder cualquier pregunta que pueda tener sobre nuestro proceso de prueba o la s\u00edfilis en s\u00ed, as\u00ed que no dude en solicitarnos m\u00e1s informaci\u00f3n.<\/p>\n<h2>\u00bfC\u00f3mo se trata la s\u00edfilis?<\/h2>\n<p>La s\u00edfilis es f\u00e1cil de tratar con antibi\u00f3ticos si se detecta a tiempo. La penicilina es el antibi\u00f3tico m\u00e1s recetado para la s\u00edfilis. Es importante tomar todas las dosis del medicamento seg\u00fan las indicaciones para eliminar por completo la infecci\u00f3n, prevenir la resistencia bacteriana al tratamiento y reducir el riesgo de da\u00f1os a largo plazo.<\/p>\n<h2>\u00bfQu\u00e9 sucede si la s\u00edfilis no se trata?<\/h2>\n<p>La s\u00edfilis no tratada puede causar problemas adicionales. Si la s\u00edfilis no se trata durante cualquiera de las etapas de los s\u00edntomas, puede propagarse a otras partes de su cuerpo:<\/p>\n<ul>\n<li>Cuando la s\u00edfilis se propaga al cerebro y al sistema nervioso, se conoce como neuros\u00edfilis. Esto puede causar fuertes dolores de cabeza, debilidad muscular, confusi\u00f3n, cambios de personalidad e incluso demencia<\/li>\n<li>La s\u00edfilis que se ha propagado al ojo se llama s\u00edfilis ocular y puede causar dolor\/enrojecimiento del ojo, da\u00f1o a la visi\u00f3n o ceguera.<\/li>\n<li>Si la s\u00edfilis se propaga a su o\u00eddo, se llama otos\u00edfilis, que puede causar p\u00e9rdida de la audici\u00f3n, zumbidos en el o\u00eddo, tinnitus, mareos o v\u00e9rtigo.<\/li>\n<\/ul>\n<h2>\u00bfPuedo volver a tener s\u00edfilis?<\/h2>\n<p>S\u00ed, puede contraer s\u00edfilis nuevamente si vuelve a estar expuesto a la infecci\u00f3n, independientemente de si su infecci\u00f3n anterior fue tratada o no. Es importante practicar continuamente el sexo seguro y hacerse la prueba con regularidad.<\/p>\n<h2>Si tengo s\u00edfilis, \u00bfqu\u00e9 le digo a mi(s) pareja(s) sexual(es)?<\/h2>\n<p>Es importante informar a cualquier pareja sexual actual y reciente sobre su diagn\u00f3stico para que tambi\u00e9n puedan hacerse la prueba de s\u00edfilis. Si no est\u00e1 seguro de c\u00f3mo abordar esta conversaci\u00f3n, nuestro personal en RealOptions puede brindarle orientaci\u00f3n y apoyo. Entendemos que estas conversaciones pueden ser dif\u00edciles, pero es esencial para proteger la salud de todos.<\/p>\n<h2>\u00bfLas pruebas y el tratamiento est\u00e1n cubiertos por Medi-Cal?<\/h2>\n<p>RealOptions Obria Medical Clinics es un proveedor de Medi-Cal, lo que significa que nuestros servicios de pruebas de ETS\/ITS para s\u00edfilis realizados por Quest Diagnostics est\u00e1n cubiertos por Medi-cal. Si su prueba de s\u00edfilis da positivo, RealOptions lo derivar\u00e1 al departamento de salud de su condado para recibir tratamiento especializado.<\/p>\n<p>\u00bfNo est\u00e1 seguro de qu\u00e9 es Medi-Cal? Es un seguro de salud de bajo costo o sin costo para los residentes de California que cumplen con ciertos requisitos de elegibilidad. Si tiene un plan de Medi-Cal, puede hacerse la prueba de s\u00edfilis y otras ETS\/ITS en RealOptions sin costo o a bajo costo. Hay algunas maneras de averiguar si califica para la cobertura de Medi-Cal si a\u00fan no est\u00e1 inscrito:<\/p>\n<ol>\n<li>Comun\u00edquese con MCAP al (800) 433-2611.<\/li>\n<li>Llame a Covered California al (800) 300-1506.<\/li>\n<li>Solicite en l\u00ednea en <a href=\"https:\/\/www.coveredca.com\/get-started\/\" data-wpel-link=\"external\" target=\"_blank\" rel=\"nofollow external noopener noreferrer\">CoveredCA.com<\/a>. por correo electr\u00f3nico con una confirmaci\u00f3n o notificaci\u00f3n para el mejor tiempo disponible.<\/li>\n<\/ol>\n<h2>Creo que podr\u00eda tener s\u00edfilis. \u00bfQu\u00e9 tengo que hacer?<\/h2>\n<p>Se debe a s\u00ed mismo tomar en serio su salud y seguridad. Ignorar la s\u00edfilis puede ser extremadamente peligroso. Si cree que puede haber estado expuesto, debe hacerse la prueba de inmediato. En Cl\u00ednicas M\u00e9dicas RealOptions Obria, podemos ayudarlo.<\/p>\n<p><a href=\"https:\/\/realoptions.net\/contact-us\/\" data-wpel-link=\"external\" target=\"_blank\" rel=\"nofollow external noopener noreferrer\">Programe una cita<\/a> para la prueba de ETS\/ITS hoy o llame al:<\/p>\n<p>400 30th St #401<br \/>\nOakland, CA 94609<br \/>\n(510) 891-9998<\/p>\n<p>1671 The Alameda #101<br \/>\nSan Jose, CA<br \/>\n(408) 978-9310<\/p>\n<p>12 N White Rd<br \/>\nSan Jose, CA<br \/>\n(408) 272-5577<\/p>\n<p>33523 Western Ave.<br \/>\nUnion City, CA 94857<br \/>\n(510) 487-4357<\/p>\n<p><em>La informaci\u00f3n m\u00e9dica sobre la s\u00edfilis es de los Centros para el Control y la Prevenci\u00f3n de Enfermedades.<\/em><\/p>\n<p><span style=\"font-weight: 400;\">https:\/\/www.cdc.gov\/std\/syphilis\/stdfact-syphilis.htm (last pulled 11\/28\/2022)<\/span><\/p>\n<p><span style=\"font-weight: 400;\">https:\/\/www.cdc.gov\/std\/syphilis\/treatment.htm (last pulled 11\/28\/2022)<\/span><\/p>\n<p><span style=\"font-weight: 400;\">https:\/\/www.cdc.gov\/std\/syphilis\/stdfact-congenital-syphilis.htm (last pulled<\/span> <span style=\"font-weight: 400;\">11\/28\/2022)<\/span><\/p>\n<p><script type=\"application\/ld+json\">\n{\n  \"@context\": \"https:\/\/schema.org\",\n  \"@type\": \"BlogPosting\",\n  \"headline\": \"Preguntas Frecuentes Sobre la S\u00edfilis\",\n  \"description\": \"Conozca los s\u00edntomas, las pruebas, el tratamiento y la prevenci\u00f3n de la s\u00edfilis. RealOptions ofrece pruebas confidenciales de ITS con soporte.\",\n  \"image\": \"https:\/\/realoptions.net\/wp-content\/uploads\/2022\/12\/sypBlog-768x513.jpg\",\n  \"author\": {\n    \"@type\": \"Organization\",\n    \"name\": \"RealOptions Obria Medical Clinics\"\n  },\n  \"publisher\": {\n    \"@type\": \"Organization\",\n    \"name\": \"RealOptions Obria Medical Clinics\",\n    \"logo\": {\n      \"@type\": \"ImageObject\",\n      \"url\": \"https:\/\/realoptions.net\/wp-content\/uploads\/2024\/06\/asfasfd-1-1-e1718949335859.webp\"\n    }\n  },\n  \"mainEntityOfPage\": {\n    \"@type\": \"WebPage\",\n    \"@id\": \"https:\/\/realoptions.net\/es\/preguntas-frecuentes-sobre-la-sifilis\/\"\n  },\n  \"datePublished\": \"2022-12-21\",\n  \"dateModified\": \"2022-12-21\",\n  \"contentLocation\": [\n    {\n      \"@type\": \"Place\",\n      \"name\": \"RealOptions Obria Medical Clinics \u2013 Central San Jose\",\n      \"address\": {\n        \"@type\": \"PostalAddress\",\n        \"streetAddress\": \"1671 The Alameda, Suite #101\",\n        \"addressLocality\": \"San Jose\",\n        \"addressRegion\": \"CA\",\n        \"postalCode\": \"95126\",\n        \"addressCountry\": \"US\"\n      },\n      \"telephone\": \"(408) 978-9310\"\n    },\n    {\n      \"@type\": \"Place\",\n      \"name\": \"RealOptions Obria Medical Clinics \u2013 East San Jose\",\n      \"address\": {\n        \"@type\": \"PostalAddress\",\n        \"streetAddress\": \"12 N. White Road, Suite #1\",\n        \"addressLocality\": \"San Jose\",\n        \"addressRegion\": \"CA\",\n        \"postalCode\": \"95127\",\n        \"addressCountry\": \"US\"\n      },\n      \"telephone\": \"(408) 272-5577\"\n    },\n    {\n      \"@type\": \"Place\",\n      \"name\": \"RealOptions Obria Medical Clinics \u2013 Oakland\",\n      \"address\": {\n        \"@type\": \"PostalAddress\",\n        \"streetAddress\": \"400 30th St, Suite #401\",\n        \"addressLocality\": \"Oakland\",\n        \"addressRegion\": \"CA\",\n        \"postalCode\": \"94609\",\n        \"addressCountry\": \"US\"\n      },\n      \"telephone\": \"(510) 891-9998\"\n    },\n    {\n      \"@type\": \"Place\",\n      \"name\": \"RealOptions Obria Medical Clinics \u2013 Union City\",\n      \"address\": {\n        \"@type\": \"PostalAddress\",\n        \"streetAddress\": \"33523 Western Ave\",\n        \"addressLocality\": \"Union City\",\n        \"addressRegion\": \"CA\",\n        \"postalCode\": \"94587\",\n        \"addressCountry\": \"US\"\n      },\n      \"telephone\": \"(510) 487-4357\"\n    }\n  ]\n}\n<\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfQu\u00e9 es la s\u00edfilis? La s\u00edfilis es una ETS que, si no se trata con cuidado, puede ser peligrosa y causar problemas a largo plazo. Para los adultos, la s\u00edfilis se divide en cuatro etapas<\/p>\n","protected":false},"author":11,"featured_media":9252,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[767],"tags":[],"class_list":["post-9250","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-preguntas-frecuentes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Preguntas Frecuentes Sobre la S\u00edfilis<\/title>\n<meta name=\"description\" content=\"Conozca los s\u00edntomas, las pruebas, el tratamiento y la prevenci\u00f3n de la s\u00edfilis. RealOptions ofrece pruebas confidenciales de ITS con soporte.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/realoptions.net\/es\/preguntas-frecuentes-sobre-la-sifilis\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Preguntas Frecuentes Sobre la S\u00edfilis\" \/>\n<meta property=\"og:description\" content=\"Conozca los s\u00edntomas, las pruebas, el tratamiento y la prevenci\u00f3n de la s\u00edfilis. RealOptions ofrece pruebas confidenciales de ITS con soporte.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/realoptions.net\/es\/preguntas-frecuentes-sobre-la-sifilis\/\" \/>\n<meta property=\"og:site_name\" content=\"RealOptions Obria Medical Clinic\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/realoptions.centralsanjose\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-21T00:41:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-20T05:58:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/realoptions.net\/wp-content\/uploads\/2022\/12\/sypBlog.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"534\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Donna Hecke\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Donna Hecke\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Preguntas Frecuentes Sobre la S\u00edfilis","description":"Conozca los s\u00edntomas, las pruebas, el tratamiento y la prevenci\u00f3n de la s\u00edfilis. RealOptions ofrece pruebas confidenciales de ITS con soporte.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/realoptions.net\/es\/preguntas-frecuentes-sobre-la-sifilis\/","og_locale":"es_ES","og_type":"article","og_title":"Preguntas Frecuentes Sobre la S\u00edfilis","og_description":"Conozca los s\u00edntomas, las pruebas, el tratamiento y la prevenci\u00f3n de la s\u00edfilis. RealOptions ofrece pruebas confidenciales de ITS con soporte.","og_url":"https:\/\/realoptions.net\/es\/preguntas-frecuentes-sobre-la-sifilis\/","og_site_name":"RealOptions Obria Medical Clinic","article_publisher":"https:\/\/www.facebook.com\/realoptions.centralsanjose\/","article_published_time":"2022-12-21T00:41:24+00:00","article_modified_time":"2026-04-20T05:58:05+00:00","og_image":[{"width":800,"height":534,"url":"https:\/\/realoptions.net\/wp-content\/uploads\/2022\/12\/sypBlog.jpg","type":"image\/jpeg"}],"author":"Donna Hecke","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Donna Hecke","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/realoptions.net\/es\/preguntas-frecuentes-sobre-la-sifilis\/#article","isPartOf":{"@id":"https:\/\/realoptions.net\/es\/preguntas-frecuentes-sobre-la-sifilis\/"},"author":{"name":"Donna Hecke","@id":"https:\/\/realoptions.net\/es\/#\/schema\/person\/dc06a2cd9b635b65999842b30a2f5dc0"},"headline":"Preguntas Frecuentes Sobre la S\u00edfilis","datePublished":"2022-12-21T00:41:24+00:00","dateModified":"2026-04-20T05:58:05+00:00","mainEntityOfPage":{"@id":"https:\/\/realoptions.net\/es\/preguntas-frecuentes-sobre-la-sifilis\/"},"wordCount":1404,"publisher":{"@id":"https:\/\/realoptions.net\/es\/#organization"},"image":{"@id":"https:\/\/realoptions.net\/es\/preguntas-frecuentes-sobre-la-sifilis\/#primaryimage"},"thumbnailUrl":"https:\/\/realoptions.net\/wp-content\/uploads\/2022\/12\/sypBlog.jpg","articleSection":["Preguntas frecuentes"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/realoptions.net\/es\/preguntas-frecuentes-sobre-la-sifilis\/","url":"https:\/\/realoptions.net\/es\/preguntas-frecuentes-sobre-la-sifilis\/","name":"Preguntas Frecuentes Sobre la S\u00edfilis","isPartOf":{"@id":"https:\/\/realoptions.net\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/realoptions.net\/es\/preguntas-frecuentes-sobre-la-sifilis\/#primaryimage"},"image":{"@id":"https:\/\/realoptions.net\/es\/preguntas-frecuentes-sobre-la-sifilis\/#primaryimage"},"thumbnailUrl":"https:\/\/realoptions.net\/wp-content\/uploads\/2022\/12\/sypBlog.jpg","datePublished":"2022-12-21T00:41:24+00:00","dateModified":"2026-04-20T05:58:05+00:00","description":"Conozca los s\u00edntomas, las pruebas, el tratamiento y la prevenci\u00f3n de la s\u00edfilis. RealOptions ofrece pruebas confidenciales de ITS con soporte.","breadcrumb":{"@id":"https:\/\/realoptions.net\/es\/preguntas-frecuentes-sobre-la-sifilis\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/realoptions.net\/es\/preguntas-frecuentes-sobre-la-sifilis\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/realoptions.net\/es\/preguntas-frecuentes-sobre-la-sifilis\/#primaryimage","url":"https:\/\/realoptions.net\/wp-content\/uploads\/2022\/12\/sypBlog.jpg","contentUrl":"https:\/\/realoptions.net\/wp-content\/uploads\/2022\/12\/sypBlog.jpg","width":800,"height":534,"caption":"Group of friends sitting outdoors on a walkway, talking and laughing together."},{"@type":"BreadcrumbList","@id":"https:\/\/realoptions.net\/es\/preguntas-frecuentes-sobre-la-sifilis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/realoptions.net\/es\/"},{"@type":"ListItem","position":2,"name":"Preguntas Frecuentes Sobre la S\u00edfilis"}]},{"@type":"WebSite","@id":"https:\/\/realoptions.net\/es\/#website","url":"https:\/\/realoptions.net\/es\/","name":"RealOptions Obria Medical Clinic","description":"","publisher":{"@id":"https:\/\/realoptions.net\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/realoptions.net\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/realoptions.net\/es\/#organization","name":"Real Options Obria Medical Clinics","url":"https:\/\/realoptions.net\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/realoptions.net\/es\/#\/schema\/logo\/image\/","url":"https:\/\/realoptions.net\/wp-content\/uploads\/2022\/04\/branding.webp","contentUrl":"https:\/\/realoptions.net\/wp-content\/uploads\/2022\/04\/branding.webp","width":450,"height":155,"caption":"Real Options Obria Medical Clinics"},"image":{"@id":"https:\/\/realoptions.net\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/realoptions.centralsanjose\/"]},{"@type":"Person","@id":"https:\/\/realoptions.net\/es\/#\/schema\/person\/dc06a2cd9b635b65999842b30a2f5dc0","name":"Donna Hecke","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/0c67ed3ebe93dcc2e75ed34103ee9b8ddea00f189e4d715f894c01be81b52329?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0c67ed3ebe93dcc2e75ed34103ee9b8ddea00f189e4d715f894c01be81b52329?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0c67ed3ebe93dcc2e75ed34103ee9b8ddea00f189e4d715f894c01be81b52329?s=96&d=mm&r=g","caption":"Donna Hecke"},"url":"https:\/\/realoptions.net\/es\/author\/donna\/"}]}},"_links":{"self":[{"href":"https:\/\/realoptions.net\/es\/wp-json\/wp\/v2\/posts\/9250","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/realoptions.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/realoptions.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/realoptions.net\/es\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/realoptions.net\/es\/wp-json\/wp\/v2\/comments?post=9250"}],"version-history":[{"count":14,"href":"https:\/\/realoptions.net\/es\/wp-json\/wp\/v2\/posts\/9250\/revisions"}],"predecessor-version":[{"id":15138,"href":"https:\/\/realoptions.net\/es\/wp-json\/wp\/v2\/posts\/9250\/revisions\/15138"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/realoptions.net\/es\/wp-json\/wp\/v2\/media\/9252"}],"wp:attachment":[{"href":"https:\/\/realoptions.net\/es\/wp-json\/wp\/v2\/media?parent=9250"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/realoptions.net\/es\/wp-json\/wp\/v2\/categories?post=9250"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/realoptions.net\/es\/wp-json\/wp\/v2\/tags?post=9250"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}